{"id":1228,"date":"2018-06-12T16:25:08","date_gmt":"2018-06-12T14:25:08","guid":{"rendered":"https:\/\/thomasdt.com\/?p=1228"},"modified":"2018-06-12T16:25:08","modified_gmt":"2018-06-12T14:25:08","slug":"mai-2018","status":"publish","type":"post","link":"https:\/\/rationalk.ch\/blog\/mai-2018\/","title":{"rendered":"Nouveaut\u00e9s Mai 2018"},"content":{"rendered":"<p>Le mois de mai (et d\u00e9but juin) a \u00e9t\u00e9 plut\u00f4t charg\u00e9 pour Rationalk.<\/p>\n<figure id=\"attachment_1231\" aria-describedby=\"caption-attachment-1231\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1231\" src=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/customer-service-1433639_640.png?resize=580%2C580&#038;ssl=1\" alt=\"3 nouveaux clients\" width=\"580\" height=\"580\" srcset=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/customer-service-1433639_640.png?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/customer-service-1433639_640.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/customer-service-1433639_640.png?resize=300%2C300&amp;ssl=1 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-1231\" class=\"wp-caption-text\">3 nouveaux clients<\/figcaption><\/figure>\n<p>Nous avons install\u00e9 deux outils de gestion de projets dans des PMEs Suisse (Vaud et Valais) dans le domaine de la construction et de l&rsquo;architecture d&rsquo;int\u00e9rieur. Et nous avons commenc\u00e9 le development d&rsquo;une plateforme sur-mesure pour une startup dans le domaine du Life-Science (Neuch\u00e2tel)<\/p>\n<p>Gr\u00e2ce au gantt et au module de gestion des resources (ce dernier est encore en beta test), il est tr\u00e8s simple de visualiser le d\u00e9roulement des projets de la soci\u00e9t\u00e9 et de v\u00e9rifier l&rsquo;\u00e9tat de charge des diff\u00e9rents collaborateurs dans la soci\u00e9t\u00e9. L&rsquo;outil de gestion des resources permet \u00e9galement de surveiller l&rsquo;utilisation de machines ou de v\u00e9hicules.<\/p>\n<p>Nous avons pu v\u00e9rifier que notre outil de gestion s&rsquo;adapte vraiment bien \u00e0 tous les domaines m\u00e9tiers et donne une grande flexibilit\u00e9 \u00e0 nos clients. L&rsquo;int\u00e9gration de petits modules ERP (tels que la gestion des produits et des clients) dans le <a href=\"https:\/\/rationalk.ch\">logiciel de gestion de projet<\/a> couvre efficacement les besoins d&rsquo;organisation de toute soci\u00e9t\u00e9 qui travaille sous forme de projet.<\/p>\n<figure id=\"attachment_1230\" aria-describedby=\"caption-attachment-1230\" style=\"width: 840px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1230\" src=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?resize=580%2C435&#038;ssl=1\" alt=\"PDCA\" width=\"580\" height=\"435\" srcset=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?resize=1568%2C1176&amp;ssl=1 1568w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?w=1160&amp;ssl=1 1160w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/plan-686327_1920.jpg?w=1740&amp;ssl=1 1740w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-1230\" class=\"wp-caption-text\">PDCA<\/figcaption><\/figure>\n<p>Nous avons apport\u00e9 plus d&rsquo;une cinquante d&rsquo;am\u00e9liorations au logiciel de gestion de\u00a0projet (am\u00e9lioration de la performance, de l&rsquo;interface utilisateur et de la s\u00e9curit\u00e9).<\/p>\n<p>L&rsquo;outil de gestion de projet h\u00e9rite d&rsquo;une nouvelle gestion des droits permettant de cloisonner certains projets priv\u00e9s.<\/p>\n<figure style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/3\/3a\/Sprachen_CH_2000_fr.png\/400px-Sprachen_CH_2000_fr.png\" alt=\"Les langues de la suisse\" width=\"400\" height=\"241\" \/><figcaption class=\"wp-caption-text\">Les langues de la suisse<\/figcaption><\/figure>\n<p>Nous avons traduit l&rsquo;outil en italien et en allemand ! Les quatres langues de la Suisse sont couvertes.<\/p>\n<p>Nous travaillons actuellement \u00e0 l&rsquo;am\u00e9lioration de l&rsquo;extranet projet. Vous savez que dans Rationalk, vous disposez d&rsquo;un espace d&rsquo;\u00e9change entre vos clients et vous. Vous pouvez y partager l&rsquo;avancement des projets ainsi que\u00a0 des documents. C&rsquo;est \u00e9galement un lieu de discussion s\u00e9curis\u00e9. Int\u00e9grer son client dans les projets est une vrai valeur ajout\u00e9e pour augmenter l&rsquo;agilit\u00e9 du projet.<\/p>\n<p>Nous avons \u00e9galement initi\u00e9 deux collaborations avec des experts m\u00e9tiers :<\/p>\n<ul>\n<li>Une premi\u00e8re collaboration sur le d\u00e9veloppement d&rsquo;un module de gestion de portefeuille de projet agile. Nous proposons des kanbans customisables pour suivre dynamiquement l&rsquo;avancement des projets. Un regroupement des projets en portefeuille de projet permet de donner une vue claire et juste \u00e0 la direction de l&rsquo;entreprise.<\/li>\n<li>La deuxi\u00e8me collaboration concerne un module de gestion de projet phase-gate. Chaque phase demande\u00a0 qu&rsquo;un certain nombre de documents soient remplis par les \u00e9quipes. Puis \u00e0 chaque jalon (gate), on signe (ou non) le passage \u00e0 la phase suivante. Les projets sont cadr\u00e9s correctement. Ce module s&rsquo;adresse aux grandes soci\u00e9t\u00e9s qui un ont bureau projet cons\u00e9quent.<\/li>\n<\/ul>\n<figure id=\"attachment_1229\" aria-describedby=\"caption-attachment-1229\" style=\"width: 613px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1229\" src=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/logoPlanning40.png?resize=580%2C571&#038;ssl=1\" alt=\"Planning 4.0\" width=\"580\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/logoPlanning40.png?w=613&amp;ssl=1 613w, https:\/\/i0.wp.com\/rationalk.ch\/blog\/wp-content\/uploads\/2018\/06\/logoPlanning40.png?resize=300%2C296&amp;ssl=1 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-1229\" class=\"wp-caption-text\">Planning 4.0<\/figcaption><\/figure>\n<p>Last but not least. <a href=\"https:\/\/planning40.com\">Planning 4.0<\/a> est sorti ! Nous avons finalis\u00e9 une version de beta\/d\u00e9mo de notre logiciel de gestion de planning de production. Nous cherchons des testeurs. Id\u00e9alement des\u00a0 usines de fabrication en Suisse romande. Appeler Thomas au 076 817 33 46.<\/p>\n<hr \/>\n<p>PS : Nous sommes toujours \u00e0 la recherche d&rsquo;un d\u00e9veloppeur pour rejoindre l&rsquo;\u00e9quipe (temps partiel et travail en remote bienvenus). Par ici pour l&rsquo;annonce:\u00a0 <a href=\"https:\/\/rationalk.ch\/jobs\">https:\/\/rationalk.ch\/jobs<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mois de mai (et d\u00e9but juin) a \u00e9t\u00e9 plut\u00f4t charg\u00e9 pour Rationalk. Nous avons install\u00e9 deux outils de gestion de projets dans des PMEs Suisse (Vaud et Valais) dans le domaine de la construction et de l&rsquo;architecture d&rsquo;int\u00e9rieur. Et nous avons commenc\u00e9 le development d&rsquo;une plateforme sur-mesure pour une startup dans le domaine du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-1228","post","type-post","status-publish","format-standard","hentry","category-rationalk"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/posts\/1228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/comments?post=1228"}],"version-history":[{"count":0,"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/posts\/1228\/revisions"}],"wp:attachment":[{"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/media?parent=1228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/categories?post=1228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rationalk.ch\/blog\/wp-json\/wp\/v2\/tags?post=1228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}